{"id":114,"count":0,"description":"","link":"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized - Bio-Textima - Bedding, Interior, Object<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized - Bio-Textima - Bedding, Interior, Object\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Bio-Textima - Bedding, Interior, Object\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/\",\"url\":\"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/\",\"name\":\"Uncategorized - Bio-Textima - Bedding, Interior, Object\",\"isPartOf\":{\"@id\":\"https:\/\/contractbeds.eu\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\/\/contractbeds.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contractbeds.eu\/en\/#website\",\"url\":\"https:\/\/contractbeds.eu\/en\/\",\"name\":\"Bio-Textima H\u00e1l\u00f3szoba Manufakt\u00fara\",\"description\":\"beds, mattresses - for hotels, accommodations\",\"publisher\":{\"@id\":\"https:\/\/contractbeds.eu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contractbeds.eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contractbeds.eu\/en\/#organization\",\"name\":\"BIO-TEXTIMA Kft.\",\"url\":\"https:\/\/contractbeds.eu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contractbeds.eu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contractbeds.eu\/wp-content\/uploads\/2021\/03\/biotex_logo.jpg\",\"contentUrl\":\"https:\/\/contractbeds.eu\/wp-content\/uploads\/2021\/03\/biotex_logo.jpg\",\"width\":335,\"height\":149,\"caption\":\"BIO-TEXTIMA Kft.\"},\"image\":{\"@id\":\"https:\/\/contractbeds.eu\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized - Bio-Textima - Bedding, Interior, Object","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized - Bio-Textima - Bedding, Interior, Object","og_url":"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/","og_site_name":"Bio-Textima - Bedding, Interior, Object","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/","url":"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/","name":"Uncategorized - Bio-Textima - Bedding, Interior, Object","isPartOf":{"@id":"https:\/\/contractbeds.eu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/contractbeds.eu\/en\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/contractbeds.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/contractbeds.eu\/en\/#website","url":"https:\/\/contractbeds.eu\/en\/","name":"Bio-Textima H\u00e1l\u00f3szoba Manufakt\u00fara","description":"beds, mattresses - for hotels, accommodations","publisher":{"@id":"https:\/\/contractbeds.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contractbeds.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/contractbeds.eu\/en\/#organization","name":"BIO-TEXTIMA Kft.","url":"https:\/\/contractbeds.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/contractbeds.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/contractbeds.eu\/wp-content\/uploads\/2021\/03\/biotex_logo.jpg","contentUrl":"https:\/\/contractbeds.eu\/wp-content\/uploads\/2021\/03\/biotex_logo.jpg","width":335,"height":149,"caption":"BIO-TEXTIMA Kft."},"image":{"@id":"https:\/\/contractbeds.eu\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/contractbeds.eu\/en\/wp-json\/wp\/v2\/product_cat\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contractbeds.eu\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/contractbeds.eu\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/contractbeds.eu\/en\/wp-json\/wp\/v2\/product?product_cat=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}